{"id":90622,"date":"2024-11-11T10:10:47","date_gmt":"2024-11-11T13:10:47","guid":{"rendered":"https:\/\/cbl.org.br\/?p=90622"},"modified":"2024-11-11T10:14:43","modified_gmt":"2024-11-11T13:14:43","slug":"participe-da-jornada-profissional-do-premio-jabuti-2024","status":"publish","type":"post","link":"https:\/\/www.cbl.org.br\/en\/2024\/11\/participe-da-jornada-profissional-do-premio-jabuti-2024\/","title":{"rendered":"Participe da Jornada Profissional do Pr\u00eamio Jabuti 2024"},"content":{"rendered":"<p>Nos dias 18 e 19 de novembro, acontece a Jornada Profissional do Pr\u00eamio Jabuti 2024. As inscri\u00e7\u00f5es para as rodadas de neg\u00f3cios entre editoras brasileiras e as editoras internacionais finalistas da categoria \u201cLivro Brasileiro Publicado no Exterior\u201d, do Pr\u00eamio Jabuti, est\u00e3o abertas. Para participar, basta <a href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLScLYY6h8IzCmzeJW-Q_DhpCjLS1igKEivT1Avmm2w_Ax49T8A\/viewform\">clicar aqui<\/a> e preencher o formul\u00e1rio.<\/p>\n<p>A iniciativa \u00e9 realizada pelo Brazilian Publishers, o programa de internacionaliza\u00e7\u00e3o da CBL com a Ag\u00eancia Brasileira de Promo\u00e7\u00e3o de Exporta\u00e7\u00f5es, a ApexBrasil. Al\u00e9m de organizar a Jornada Profissional da premia\u00e7\u00e3o e trazer o grupo de editores ao Brasil, o programa promove a categoria \u2013 que, desde 2017, condecora a editora brasileira, respons\u00e1vel pela publica\u00e7\u00e3o nacional do livro ganhador; e a internacional, que adquiriu esses direitos e publicou a obra em outro idioma.<\/p>\n<p>O evento \u00e9 gratuito e re\u00fane exclusivamente publishers globais previamente interessadas em descobrir novas hist\u00f3rias brasileiras. As inscri\u00e7\u00f5es ficam abertas at\u00e9 o dia 13 de novembro.<\/p>\n<p>Editoras n\u00e3o participantes do Brazilian Publishers tamb\u00e9m podem se inscrever de maneira gratuita, basta preencher o Termo de Ades\u00e3o em anexo no formul\u00e1rio de inscri\u00e7\u00e3o e enviar para o e-mail anaclaudia@cbl.org.br.<\/p>\n<p><strong>Sobre o Brazilian Publishers<\/strong><br \/>\nCriado em 2008, o Brazilian Publishers \u00e9 um projeto setorial de fomento \u00e0s exporta\u00e7\u00f5es de conte\u00fado editorial brasileiro, que visa promover o setor no mercado global de maneira orientada e articulada. A iniciativa \u00e9 resultado da parceria entre a C\u00e2mara Brasileira do Livro (CBL) e a Ag\u00eancia Brasileira de Promo\u00e7\u00e3o de Exporta\u00e7\u00f5es e Investimentos (ApexBrasil), que atua para promover os produtos e servi\u00e7os brasileiros no exterior e atrair investimentos estrangeiros para setores estrat\u00e9gicos da economia brasileira por meio de a\u00e7\u00f5es de promo\u00e7\u00e3o comercial. As iniciativas que contemplam as feiras internacionais do calend\u00e1rio com estande pr\u00f3prio contam, ainda, com o apoio do Minist\u00e9rio das Rela\u00e7\u00f5es Exteriores, o MRE. Tem interesse em participar do Brazilian Publishers? Ent\u00e3o entre em contato com a Ana Claudia Paiva por meio do e-mail: anaclaudia@cbl.org.br e realize a ades\u00e3o ao Programa.<\/p>","protected":false},"excerpt":{"rendered":"<p>Nos dias 18 e 19 de novembro, acontece a Jornada Profissional do Pr\u00eamio Jabuti 2024. As inscri\u00e7\u00f5es para as rodadas de neg\u00f3cios entre editoras brasileiras e as editoras internacionais finalistas da categoria \u201cLivro Brasileiro Publicado no Exterior\u201d, do Pr\u00eamio Jabuti, est\u00e3o abertas. Para participar, basta clicar aqui e preencher o formul\u00e1rio. A iniciativa \u00e9 realizada [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":90623,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-90622","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nao-categorizado"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.cbl.org.br\/en\/wp-json\/wp\/v2\/posts\/90622","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cbl.org.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cbl.org.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cbl.org.br\/en\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cbl.org.br\/en\/wp-json\/wp\/v2\/comments?post=90622"}],"version-history":[{"count":2,"href":"https:\/\/www.cbl.org.br\/en\/wp-json\/wp\/v2\/posts\/90622\/revisions"}],"predecessor-version":[{"id":90625,"href":"https:\/\/www.cbl.org.br\/en\/wp-json\/wp\/v2\/posts\/90622\/revisions\/90625"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cbl.org.br\/en\/wp-json\/wp\/v2\/media\/90623"}],"wp:attachment":[{"href":"https:\/\/www.cbl.org.br\/en\/wp-json\/wp\/v2\/media?parent=90622"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cbl.org.br\/en\/wp-json\/wp\/v2\/categories?post=90622"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cbl.org.br\/en\/wp-json\/wp\/v2\/tags?post=90622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}